{"id":2403,"date":"2018-05-04T16:33:29","date_gmt":"2018-05-04T16:33:29","guid":{"rendered":"http:\/\/radiotemuco.com\/home\/?p=2403"},"modified":"2018-05-04T16:33:29","modified_gmt":"2018-05-04T16:33:29","slug":"artistas-locales-presentan-mas-de-50-obras-en-vision-nocturna-en-hall-central-de-santo-tomas-temuco","status":"publish","type":"post","link":"https:\/\/radiotemuco.com\/home\/artistas-locales-presentan-mas-de-50-obras-en-vision-nocturna-en-hall-central-de-santo-tomas-temuco\/","title":{"rendered":"Artistas locales presentan m\u00e1s de 50 obras en \u201cVisi\u00f3n Nocturna\u201d en hall central de Santo Tom\u00e1s Temuco"},"content":{"rendered":"<p>La muestra de pinturas estar\u00e1 disponible para el p\u00fablico durante todo el mes de mayo, de lunes a s\u00e1bado en la sede de Santo Tom\u00e1s ubicada en calle Manuel Rodr\u00edguez 060.<\/p>\n<p>Con una concurrida ceremonia, fue inaugurada la muestra \u201cVisi\u00f3n Nocturna\u201d que congrega obras de cinco artistas de La Araucan\u00eda, como parte del ciclo 2018 de \u201cSanto Tom\u00e1s en el Arte\u201d, en el hall central de la casa de estudios.<br \/>\nSon 55 cuadros que enlazan una diversidad de formatos y formas de trabajar la pintura en un montaje realizado bajo la oscuridad de la noche, que evoca imposibilidad de comunicaci\u00f3n y la idea de di\u00e1logo. Como apuntan los artistas Francisco Badilla, Claudio Petit-Laurent, Rodrigo Gallardo, Leonardo Cravero y Alex Mellado.<br \/>\nDurante la inauguraci\u00f3n de la muestra, la directora acad\u00e9mica del Centro de Formaci\u00f3n T\u00e9cnica e Instituto Profesional, Marie Oriette C\u00e1ceres, destac\u00f3 el aporte que entrega la apertura al arte para la formaci\u00f3n de los j\u00f3venes.<br \/>\n\u201cEs parte de la formaci\u00f3n de nuestros estudiantes, nos interesa ir m\u00e1s all\u00e1 de lo disciplinario con una formaci\u00f3n integral que incluye el arte, y en esta oportunidad con la pintura\u201d. Puntualiz\u00f3 la acad\u00e9mica.<br \/>\nEn representaci\u00f3n de los artistas que presentan sus obras en el hall central de la sede Santo Tom\u00e1s Temuco, \u00c1lex Mellado Larra\u00edn entreg\u00f3 detalles de los estilos que convergen en la exposici\u00f3n.<br \/>\n\u201cLa reuni\u00f3n de cinco artistas que desarrollan proyectos independientes, por lo tanto nuestro objetivo es desarrollar un proyecto ideado para el muro donde nos invitan a exponer desde el concepto de la acumulaci\u00f3n y la fricci\u00f3n de las ideas de di\u00e1logo de nosotros como colectivo.\u201d<br \/>\n\u201cVisi\u00f3n Nocturna\u201d agrega una exposici\u00f3n audiovisual que detalla el trabajo de montaje previo que se realiz\u00f3 durante la noche, con ausencia de luces, como una b\u00fasqueda de distancia de la forma tradicional de exponer en los muros.<br \/>\nLa muestra art\u00edstica estar\u00e1 disponible para el p\u00fablico durante todo el mes de mayo de lunes a s\u00e1bado de 09:00 a 19:00 hrs. En la sede de Santo Tom\u00e1s ubicada en calle Manuel Rodr\u00edguez 060.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La muestra de pinturas estar\u00e1 disponible para el p\u00fablico durante todo el mes de mayo, de lunes a s\u00e1bado en la sede de Santo Tom\u00e1s ubicada en calle Manuel Rodr\u00edguez 060. Con una concurrida ceremonia, fue inaugurada la muestra \u201cVisi\u00f3n Nocturna\u201d que congrega obras de cinco artistas de La Araucan\u00eda, como parte del ciclo 2018 de \u201cSanto Tom\u00e1s en el Arte\u201d, en el hall central de la casa de estudios. Son 55 cuadros que enlazan una diversidad de formatos y formas de trabajar la pintura en un montaje realizado bajo la oscuridad de la noche, que evoca imposibilidad de comunicaci\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2404,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-regionales"],"jetpack_featured_media_url":"https:\/\/radiotemuco.com\/home\/wp-content\/uploads\/2018\/05\/33.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":1,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"predecessor-version":[{"id":2405,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/2403\/revisions\/2405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/media\/2404"}],"wp:attachment":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}