{"id":21246,"date":"2024-10-03T18:06:32","date_gmt":"2024-10-03T18:06:32","guid":{"rendered":"https:\/\/radiotemuco.com\/home\/?p=21246"},"modified":"2024-10-03T18:06:32","modified_gmt":"2024-10-03T18:06:32","slug":"pdi-detuvo-a-mujer-por-microtrafico-de-drogas-e-infraccion-a-la-ley-de-armas-en-villarrica","status":"publish","type":"post","link":"https:\/\/radiotemuco.com\/home\/pdi-detuvo-a-mujer-por-microtrafico-de-drogas-e-infraccion-a-la-ley-de-armas-en-villarrica\/","title":{"rendered":"PDI detuvo a mujer por microtr\u00e1fico de drogas e infracci\u00f3n a la Ley de Armas en Villarrica"},"content":{"rendered":"<p>Detectives del equipo Modelo Territorial Cero (MT0) de la Brigada de Investigaci\u00f3n Criminal (Bicrim) Villarrica, detuvieron a una mujer -con antecedentes policiales-, por los delitos flagrantes de microtr\u00e1fico de drogas, posesi\u00f3n o tenencia ilegal de arma y munici\u00f3n, adem\u00e1s del incumplimiento de una medida de arresto domiciliario nocturno, vigente en su contra por tr\u00e1fico de drogas en peque\u00f1as cantidades, en la misma comuna.<\/p>\n<p>El subcomisario Alex Rojas de la Bicrim Villarrica, explic\u00f3 los detectives del Equipo MT-comenzaron la indagatoria, en coordinaci\u00f3n con la Fiscal\u00eda Local de la comuna, en el marco de una orden de investigar asociada a la comercializaci\u00f3n de sustancias controladas por la Ley 20.000 en la zona lacustre, logrando la detenci\u00f3n de la imputada, en flagrancia.<\/p>\n<p>\u201cCon este procedimiento se logr\u00f3 la incautaci\u00f3n de dosis de coca\u00edna base, clorhidrato de coca\u00edna, un arma de fuego tipo rev\u00f3lver y municiones, adem\u00e1s de especies asociadas directamente al il\u00edcito investigado\u201d, agreg\u00f3 el subcomisario Rojas.<\/p>\n<p>Los antecedentes fueron puestos a disposici\u00f3n del fiscal a cargo de la investigaci\u00f3n, qui\u00e9n instruy\u00f3 que la detenida fuera puesta a disposici\u00f3n del Juzgado de Garant\u00eda de Villarrica, para su respectivo control de detenci\u00f3n el d\u00eda de hoy 3 de octubre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detectives del equipo Modelo Territorial Cero (MT0) de la Brigada de Investigaci\u00f3n Criminal (Bicrim) Villarrica, detuvieron a una mujer -con antecedentes policiales-, por los delitos flagrantes de microtr\u00e1fico de drogas, posesi\u00f3n o tenencia ilegal de arma y munici\u00f3n, adem\u00e1s del incumplimiento de una medida de arresto domiciliario nocturno, vigente en su contra por tr\u00e1fico de drogas en peque\u00f1as cantidades, en la misma comuna. El subcomisario Alex Rojas de la Bicrim Villarrica, explic\u00f3 los detectives del Equipo MT-comenzaron la indagatoria, en coordinaci\u00f3n con la Fiscal\u00eda Local de la comuna, en el marco de una orden de investigar asociada a la comercializaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21247,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,7,2],"tags":[],"class_list":["post-21246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","category-nacional","category-regionales"],"jetpack_featured_media_url":"https:\/\/radiotemuco.com\/home\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-03-at-11.57.55.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/21246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/comments?post=21246"}],"version-history":[{"count":1,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/21246\/revisions"}],"predecessor-version":[{"id":21248,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/21246\/revisions\/21248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/media\/21247"}],"wp:attachment":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/media?parent=21246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/categories?post=21246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/tags?post=21246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}