{"id":19123,"date":"2024-01-05T13:34:14","date_gmt":"2024-01-05T13:34:14","guid":{"rendered":"https:\/\/radiotemuco.com\/home\/?p=19123"},"modified":"2024-01-05T13:34:14","modified_gmt":"2024-01-05T13:34:14","slug":"la-fiesta-del-triatlon-en-pucon-se-inauguro-con-el-carozzi-kids-challenge-2024","status":"publish","type":"post","link":"https:\/\/radiotemuco.com\/home\/la-fiesta-del-triatlon-en-pucon-se-inauguro-con-el-carozzi-kids-challenge-2024\/","title":{"rendered":"La fiesta del triatl\u00f3n en Puc\u00f3n se inaugur\u00f3 con el Carozzi Kids Challenge 2024"},"content":{"rendered":"<p style=\"font-weight: 400;\">Con el objetivo de fomentar la disciplina del triatl\u00f3n desde temprana edad, el Club Deportivo de Universidad Cat\u00f3lica (CDUC) llev\u00f3 a cabo este jueves 4 de enero la tradicional competencia Carrozzi Kids Challenge. La carrera, que tiene como protagonistas al semillero del triatl\u00f3n nacional, tuvo como grandes ganadores de la largada principal (que considera las edades entre los 16 y los 19 a\u00f1os) a Sebasti\u00e1n Zurob (00:32:39) y Dominga J\u00e1come (00:36:58).<\/p>\n<p style=\"font-weight: 400;\">En la competencia participan ni\u00f1os y j\u00f3venes desde los 7 hasta los 19 a\u00f1os y cada categor\u00eda cuenta con circuitos que contemplan nataci\u00f3n, ciclismo y trote con distancias acorde a cada edad. En la actividad, los peque\u00f1os triatletas disfrutan transform\u00e1ndose en \u201cni\u00f1os de acero\u201d en el marco de \u201cLa Carrera M\u00e1s Linda del Mundo\u201d.<\/p>\n<p style=\"font-weight: 400;\">En la categor\u00eda varones de 18-19 a\u00f1os, result\u00f3 campe\u00f3n el triatleta Ignacio Flores (00:33:10), seguido de Daniel Ubilla (00:33:35) y cerrando el podio Sebasti\u00e1n Colillanca (00:33:42). Cabe destacar que Zurob al pertenecer a la categor\u00eda 16-17 a\u00f1os, larg\u00f3 30 segundos despu\u00e9s que Flores a quien super\u00f3 en la clasificaci\u00f3n general al escoltarlo por mil\u00e9simas. En damas, en tanto, Dominga J\u00e1come fue campeona en la categor\u00eda 18-19 a\u00f1os (00:36:58), escoltada por Sol Ottenhsimer (00:39:00) y Victoria Rubio (00:39:54), quien concluy\u00f3 tercera.<\/p>\n<p style=\"font-weight: 400;\">En paralelo, para este viernes 5 de enero est\u00e1 programado el Carozzi Promotional Race, la segunda gran prueba que antecede al IRONMAN 70.3 de Puc\u00f3n. En esta carrera participan deportistas amateurs y principiantes, desde los 18 hasta 50 a\u00f1os o m\u00e1s. Una instancia en la que algunos de los deportistas estar\u00e1n viviendo sus primeras experiencias en el triatl\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">Finalmente, es importante destacar que este evento deportivo se realiz\u00f3 gracias al trabajo y colaboraci\u00f3n de las municipalidades de Puc\u00f3n y Curarrehue.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de fomentar la disciplina del triatl\u00f3n desde temprana edad, el Club Deportivo de Universidad Cat\u00f3lica (CDUC) llev\u00f3 a cabo este jueves 4 de enero la tradicional competencia Carrozzi Kids Challenge. La carrera, que tiene como protagonistas al semillero del triatl\u00f3n nacional, tuvo como grandes ganadores de la largada principal (que considera las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19124,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,8,7,2],"tags":[],"class_list":["post-19123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportivas","category-internacional","category-nacional","category-regionales"],"jetpack_featured_media_url":"https:\/\/radiotemuco.com\/home\/wp-content\/uploads\/2024\/01\/JACOME-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/19123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/comments?post=19123"}],"version-history":[{"count":1,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/19123\/revisions"}],"predecessor-version":[{"id":19125,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/posts\/19123\/revisions\/19125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/media\/19124"}],"wp:attachment":[{"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/media?parent=19123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/categories?post=19123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotemuco.com\/home\/wp-json\/wp\/v2\/tags?post=19123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}